{"id":2122,"date":"2024-04-09T17:26:15","date_gmt":"2024-04-09T17:26:15","guid":{"rendered":"https:\/\/niveluno.com\/?p=2122"},"modified":"2024-04-09T17:26:15","modified_gmt":"2024-04-09T17:26:15","slug":"comision-de-quejas-y-denuncias-ordena-modificar-5-mananeras-mas","status":"publish","type":"post","link":"https:\/\/niveluno.com\/index.php\/2024\/04\/09\/comision-de-quejas-y-denuncias-ordena-modificar-5-mananeras-mas\/","title":{"rendered":"Comisi\u00f3n de Quejas y Denuncias Ordena Modificar 5 Ma\u00f1aneras m\u00e1s"},"content":{"rendered":"<p>La Comisi\u00f3n de Quejas y Denuncias orden\u00f3 al presidente Andr\u00e9s Manuel L\u00f3pez Obrador eliminar o modificar varias de sus conferencias matutinas emitidas en marzo y abril, debido a que contienen expresiones de \u00edndole electoral y propaganda gubernamental prohibida en tiempos de campa\u00f1a.<\/p>\n<p>En una sesi\u00f3n que se prolong\u00f3 hasta la medianoche, la Comisi\u00f3n determin\u00f3 que las ma\u00f1aneras del 7, 11, 12 y 22 de marzo, as\u00ed como del 1 de abril, deben ser ajustadas para evitar generar ventajas indebidas o afectaciones a ciertas fuerzas pol\u00edticas.<\/p>\n<p>Se descart\u00f3 la necesidad de modificar la conferencia del 13 de marzo, al considerar que no estaba relacionada con el proceso electoral. Sin embargo, se se\u00f1al\u00f3 que las ma\u00f1aneras del 7, 11 y 12 de marzo incluyeron referencias a las elecciones y a logros del gobierno, lo que podr\u00eda generar inequidad en la contienda.<\/p>\n<p>Asimismo, se denunci\u00f3 el uso indebido de recursos p\u00fablicos en la ma\u00f1anera del 22 de marzo, donde se abordaron temas de programas sociales. Aunque se descart\u00f3 la eliminaci\u00f3n de ciertos fragmentos, se orden\u00f3 ajustar las acciones de gobierno y programas sociales que puedan incidir en el proceso electoral.<\/p>\n<p>En el caso de la conferencia del 1 de abril, se se\u00f1al\u00f3 la emisi\u00f3n de manifestaciones que podr\u00edan vulnerar los principios de imparcialidad y equidad en el proceso electoral, as\u00ed como la difusi\u00f3n de propaganda indebida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Quejas y Denuncias orden\u00f3 al presidente Andr\u00e9s Manuel L\u00f3pez Obrador eliminar o modificar varias de sus conferencias matutinas emitidas en marzo y abril, debido a que contienen expresiones de \u00edndole electoral y propaganda gubernamental prohibida en tiempos de campa\u00f1a. En una sesi\u00f3n que se prolong\u00f3 hasta la medianoche, la Comisi\u00f3n determin\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"amp_status":""},"categories":[541],"tags":[1574,1045,1575,985,1576],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2122"}],"collection":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":1,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":2124,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions\/2124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/media\/2123"}],"wp:attachment":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}