{"id":2083,"date":"2024-04-08T15:16:36","date_gmt":"2024-04-08T15:16:36","guid":{"rendered":"https:\/\/niveluno.com\/?p=2083"},"modified":"2024-04-08T15:19:36","modified_gmt":"2024-04-08T15:19:36","slug":"mexico-busca-justicia-ante-la-cij-por-asalto-a-embajada-en-ecuador","status":"publish","type":"post","link":"https:\/\/niveluno.com\/index.php\/2024\/04\/08\/mexico-busca-justicia-ante-la-cij-por-asalto-a-embajada-en-ecuador\/","title":{"rendered":"M\u00e9xico busca justicia ante la CIJ por asalto a embajada en Ecuador"},"content":{"rendered":"<p>La canciller\u00eda mexicana conf\u00eda en que la Corte Internacional de Justicia (CIJ) de La Haya exhorte al Estado ecuatoriano a reparar el da\u00f1o causado por el reciente asalto a la embajada mexicana en Quito. As\u00ed lo afirm\u00f3 ayer la canciller Alicia B\u00e1rcena.<\/p>\n<p>En una rueda de prensa en el Aeropuerto Internacional de la Ciudad de M\u00e9xico, B\u00e1rcena dio la bienvenida a la embajadora Raquel Serur y al personal diplom\u00e1tico acreditado en Ecuador, quienes regresaron a salvo junto con sus familias y mascotas. Destac\u00f3 el esfuerzo de la misi\u00f3n mexicana y la solidaridad pol\u00edtica del pa\u00eds ante este lamentable suceso.<\/p>\n<p>B\u00e1rcena anunci\u00f3 que M\u00e9xico presentar\u00e1 la demanda ante la CIJ este lunes y buscar\u00e1 el respaldo de la comunidad internacional. Adem\u00e1s, reiter\u00f3 que el ex vicepresidente ecuatoriano Jorge Glas contin\u00faa siendo un asilado pol\u00edtico de M\u00e9xico.<\/p>\n<p>La canciller tambi\u00e9n se\u00f1al\u00f3 que, debido al rompimiento de relaciones, se congelar\u00e1n programas de apoyo a migrantes ecuatorianos y las conversaciones sobre comercio internacional con Ecuador.<\/p>\n<p>Por otro lado, B\u00e1rcena afirm\u00f3 que M\u00e9xico no tiene planes de expulsar al personal diplom\u00e1tico ecuatoriano del pa\u00eds y asegur\u00f3 que se brindar\u00e1 apoyo a los ciudadanos mexicanos en Ecuador a trav\u00e9s del Sistema de Registro para Personas Mexicanas en el Exterior y las embajadas en Chile, Colombia y Per\u00fa.<\/p>\n<p>El asalto a la embajada mexicana en Quito ha generado un fuerte impacto diplom\u00e1tico, pero M\u00e9xico busca justicia y protecci\u00f3n para sus ciudadanos en el extranjero.<\/p>\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-mlfrj-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-mlfrj-1n7m0yu\">\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-49\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 juice:gap-4 juice:md:gap-6 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"6c4c088d-fadf-4acd-bb4b-e4db2e3c8a49\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>CorteInternacionalDeJusticia, AsaltoEmbajada, RelacionesInternacionales, M\u00e9xico, Ecuador<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La canciller\u00eda mexicana conf\u00eda en que la Corte Internacional de Justicia (CIJ) de La Haya exhorte al Estado ecuatoriano a reparar el da\u00f1o causado por el reciente asalto a la embajada mexicana en Quito. As\u00ed lo afirm\u00f3 ayer la canciller Alicia B\u00e1rcena. En una rueda de prensa en el Aeropuerto Internacional de la Ciudad de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"amp_status":""},"categories":[541],"tags":[1555,1351,1050,567,1524],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2083"}],"collection":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/comments?post=2083"}],"version-history":[{"count":1,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2083\/revisions"}],"predecessor-version":[{"id":2084,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/posts\/2083\/revisions\/2084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/media\/2085"}],"wp:attachment":[{"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/media?parent=2083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/categories?post=2083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niveluno.com\/index.php\/wp-json\/wp\/v2\/tags?post=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}